{"id":43640,"date":"2021-02-20T12:46:52","date_gmt":"2021-02-20T05:46:52","guid":{"rendered":"https:\/\/deepquest.code511.com\/blog\/2021\/02\/backdoor-win32-darkkomet-apcc-insecure-permissions\/"},"modified":"2021-02-20T12:46:52","modified_gmt":"2021-02-20T05:46:52","slug":"backdoor-win32-darkkomet-apcc-insecure-permissions","status":"publish","type":"post","link":"https:\/\/deepquest.code511.com\/blog\/2021\/02\/backdoor-win32-darkkomet-apcc-insecure-permissions\/","title":{"rendered":"Backdoor.Win32.DarkKomet.apcc Insecure Permissions"},"content":{"rendered":"<p>Backdoor.Win32.DarkKomet.apcc malware suffers from an insecure permissions vulnerability.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Backdoor.Win32.DarkKomet.apcc malware suffers from an insecure permissions vulnerability.<\/p>\n","protected":false},"author":439,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_analysis_target_kw":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[43],"tags":[],"class_list":["post-43640","post","type-post","status-publish","format-standard","hentry","category-exploit"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p4bBYZ-blS","_links":{"self":[{"href":"https:\/\/deepquest.code511.com\/blog\/wp-json\/wp\/v2\/posts\/43640","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/deepquest.code511.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/deepquest.code511.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/deepquest.code511.com\/blog\/wp-json\/wp\/v2\/users\/439"}],"replies":[{"embeddable":true,"href":"https:\/\/deepquest.code511.com\/blog\/wp-json\/wp\/v2\/comments?post=43640"}],"version-history":[{"count":0,"href":"https:\/\/deepquest.code511.com\/blog\/wp-json\/wp\/v2\/posts\/43640\/revisions"}],"wp:attachment":[{"href":"https:\/\/deepquest.code511.com\/blog\/wp-json\/wp\/v2\/media?parent=43640"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/deepquest.code511.com\/blog\/wp-json\/wp\/v2\/categories?post=43640"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/deepquest.code511.com\/blog\/wp-json\/wp\/v2\/tags?post=43640"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}