{"id":35773,"date":"2019-01-15T08:57:48","date_gmt":"2019-01-15T01:57:48","guid":{"rendered":"http:\/\/deepquest.code511.com\/blog\/2019\/01\/microsoft-windows-dssvc-movefileinheritsecurity-privilege-escalation\/"},"modified":"2019-01-15T08:57:48","modified_gmt":"2019-01-15T01:57:48","slug":"microsoft-windows-dssvc-movefileinheritsecurity-privilege-escalation","status":"publish","type":"post","link":"https:\/\/deepquest.code511.com\/blog\/2019\/01\/microsoft-windows-dssvc-movefileinheritsecurity-privilege-escalation\/","title":{"rendered":"Microsoft Windows DSSVC MoveFileInheritSecurity Privilege Escalation"},"content":{"rendered":"<p>Microsoft Windows suffers from DSSVC MoveFileInheritSecurity privilege escalation vulnerabilities.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Microsoft Windows suffers from DSSVC MoveFileInheritSecurity privilege escalation vulnerabilities.<\/p>\n","protected":false},"author":439,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_analysis_target_kw":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[43],"tags":[],"class_list":["post-35773","post","type-post","status-publish","format-standard","hentry","category-exploit"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p4bBYZ-9iZ","_links":{"self":[{"href":"https:\/\/deepquest.code511.com\/blog\/wp-json\/wp\/v2\/posts\/35773","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/deepquest.code511.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/deepquest.code511.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/deepquest.code511.com\/blog\/wp-json\/wp\/v2\/users\/439"}],"replies":[{"embeddable":true,"href":"https:\/\/deepquest.code511.com\/blog\/wp-json\/wp\/v2\/comments?post=35773"}],"version-history":[{"count":0,"href":"https:\/\/deepquest.code511.com\/blog\/wp-json\/wp\/v2\/posts\/35773\/revisions"}],"wp:attachment":[{"href":"https:\/\/deepquest.code511.com\/blog\/wp-json\/wp\/v2\/media?parent=35773"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/deepquest.code511.com\/blog\/wp-json\/wp\/v2\/categories?post=35773"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/deepquest.code511.com\/blog\/wp-json\/wp\/v2\/tags?post=35773"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}