{"id":35597,"date":"2019-01-04T06:35:38","date_gmt":"2019-01-03T23:35:38","guid":{"rendered":"http:\/\/deepquest.code511.com\/blog\/2019\/01\/typo3-cms-twwc_pages-8-7-x-database-disclosure\/"},"modified":"2019-01-04T06:35:38","modified_gmt":"2019-01-03T23:35:38","slug":"typo3-cms-twwc_pages-8-7-x-database-disclosure","status":"publish","type":"post","link":"https:\/\/deepquest.code511.com\/blog\/2019\/01\/typo3-cms-twwc_pages-8-7-x-database-disclosure\/","title":{"rendered":"Typo3 CMS twwc_pages 8.7.x Database Disclosure"},"content":{"rendered":"<p>Typo3 CMS twwc_pages extension version 8.7.x suffers from a database disclosure vulnerability.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Typo3 CMS twwc_pages extension version 8.7.x suffers from a database disclosure vulnerability.<\/p>\n","protected":false},"author":439,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_analysis_target_kw":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[43],"tags":[],"class_list":["post-35597","post","type-post","status-publish","format-standard","hentry","category-exploit"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p4bBYZ-9g9","_links":{"self":[{"href":"https:\/\/deepquest.code511.com\/blog\/wp-json\/wp\/v2\/posts\/35597","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/deepquest.code511.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/deepquest.code511.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/deepquest.code511.com\/blog\/wp-json\/wp\/v2\/users\/439"}],"replies":[{"embeddable":true,"href":"https:\/\/deepquest.code511.com\/blog\/wp-json\/wp\/v2\/comments?post=35597"}],"version-history":[{"count":0,"href":"https:\/\/deepquest.code511.com\/blog\/wp-json\/wp\/v2\/posts\/35597\/revisions"}],"wp:attachment":[{"href":"https:\/\/deepquest.code511.com\/blog\/wp-json\/wp\/v2\/media?parent=35597"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/deepquest.code511.com\/blog\/wp-json\/wp\/v2\/categories?post=35597"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/deepquest.code511.com\/blog\/wp-json\/wp\/v2\/tags?post=35597"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}