{"id":35338,"date":"2018-12-13T02:21:39","date_gmt":"2018-12-12T19:21:39","guid":{"rendered":"http:\/\/deepquest.code511.com\/blog\/2018\/12\/printeron-enterprise-4-1-4-arbitrary-file-deletion\/"},"modified":"2018-12-13T02:21:39","modified_gmt":"2018-12-12T19:21:39","slug":"printeron-enterprise-4-1-4-arbitrary-file-deletion","status":"publish","type":"post","link":"https:\/\/deepquest.code511.com\/blog\/2018\/12\/printeron-enterprise-4-1-4-arbitrary-file-deletion\/","title":{"rendered":"PrinterOn Enterprise 4.1.4 Arbitrary File Deletion"},"content":{"rendered":"<p>PrinterOn Enterprise version 4.1.4 suffers from an arbitrary file deletion vulnerability.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>PrinterOn Enterprise version 4.1.4 suffers from an arbitrary file deletion vulnerability.<\/p>\n","protected":false},"author":439,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_analysis_target_kw":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[43],"tags":[],"class_list":["post-35338","post","type-post","status-publish","format-standard","hentry","category-exploit"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p4bBYZ-9bY","_links":{"self":[{"href":"https:\/\/deepquest.code511.com\/blog\/wp-json\/wp\/v2\/posts\/35338","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/deepquest.code511.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/deepquest.code511.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/deepquest.code511.com\/blog\/wp-json\/wp\/v2\/users\/439"}],"replies":[{"embeddable":true,"href":"https:\/\/deepquest.code511.com\/blog\/wp-json\/wp\/v2\/comments?post=35338"}],"version-history":[{"count":0,"href":"https:\/\/deepquest.code511.com\/blog\/wp-json\/wp\/v2\/posts\/35338\/revisions"}],"wp:attachment":[{"href":"https:\/\/deepquest.code511.com\/blog\/wp-json\/wp\/v2\/media?parent=35338"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/deepquest.code511.com\/blog\/wp-json\/wp\/v2\/categories?post=35338"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/deepquest.code511.com\/blog\/wp-json\/wp\/v2\/tags?post=35338"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}