{"id":35005,"date":"2018-11-15T00:00:00","date_gmt":"2018-11-15T07:00:00","guid":{"rendered":"http:\/\/deepquest.code511.com\/blog\/2018\/11\/dos-notepad3-1-0-2-350-denial-of-service-poc\/"},"modified":"2018-11-15T00:00:00","modified_gmt":"2018-11-15T07:00:00","slug":"dos-notepad3-1-0-2-350-denial-of-service-poc","status":"publish","type":"post","link":"https:\/\/deepquest.code511.com\/blog\/2018\/11\/dos-notepad3-1-0-2-350-denial-of-service-poc\/","title":{"rendered":"[dos] Notepad3 1.0.2.350 &#8211; Denial of Service (PoC)"},"content":{"rendered":"<p>Notepad3 1.0.2.350 &#8211; Denial of Service (PoC)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Notepad3 1.0.2.350 &#8211; Denial of Service (PoC)<\/p>\n","protected":false},"author":439,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_analysis_target_kw":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[3],"tags":[25,2862],"class_list":["post-35005","post","type-post","status-publish","format-standard","hentry","category-security","tag-0day","tag-remote-exploit"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p4bBYZ-96B","_links":{"self":[{"href":"https:\/\/deepquest.code511.com\/blog\/wp-json\/wp\/v2\/posts\/35005","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/deepquest.code511.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/deepquest.code511.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/deepquest.code511.com\/blog\/wp-json\/wp\/v2\/users\/439"}],"replies":[{"embeddable":true,"href":"https:\/\/deepquest.code511.com\/blog\/wp-json\/wp\/v2\/comments?post=35005"}],"version-history":[{"count":0,"href":"https:\/\/deepquest.code511.com\/blog\/wp-json\/wp\/v2\/posts\/35005\/revisions"}],"wp:attachment":[{"href":"https:\/\/deepquest.code511.com\/blog\/wp-json\/wp\/v2\/media?parent=35005"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/deepquest.code511.com\/blog\/wp-json\/wp\/v2\/categories?post=35005"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/deepquest.code511.com\/blog\/wp-json\/wp\/v2\/tags?post=35005"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}