{"id":15729,"date":"2014-06-24T21:29:43","date_gmt":"2014-06-24T14:29:43","guid":{"rendered":"http:\/\/deepquest.code511.com\/blog\/2014\/06\/httpwww-bobia-go-thnews_files_attnews_1403299125%5d-txt\/"},"modified":"2014-06-24T21:29:43","modified_gmt":"2014-06-24T14:29:43","slug":"httpwww-bobia-go-thnews_files_attnews_1403299125%5d-txt","status":"publish","type":"post","link":"https:\/\/deepquest.code511.com\/blog\/2014\/06\/httpwww-bobia-go-thnews_files_attnews_1403299125%5d-txt\/","title":{"rendered":"http:\/\/www.bobia.go.th\/news_files_att\/news_1403299125%5D.txt"},"content":{"rendered":"<p>http:\/\/www.bobia.go.th\/news_files_att\/news_1403299125%5D.txt notified by Ashiyane Digital Security Team<\/p>\n","protected":false},"excerpt":{"rendered":"<p>http:\/\/www.bobia.go.th\/news_files_att\/news_1403299125%5D.txt notified by Ashiyane Digital Security Team<\/p>\n","protected":false},"author":439,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"_seopress_robots_primary_cat":"","_seopress_titles_title":"","_seopress_titles_desc":"","_seopress_robots_index":"","_seopress_analysis_target_kw":"","_jetpack_newsletter_access":"","_jetpack_dont_email_post_to_subs":false,"_jetpack_newsletter_tier_id":0,"_jetpack_memberships_contains_paywalled_content":false,"_jetpack_memberships_contains_paid_content":false,"footnotes":"","jetpack_post_was_ever_published":false},"categories":[3],"tags":[2879],"class_list":["post-15729","post","type-post","status-publish","format-standard","hentry","category-security","tag-defacement"],"jetpack_featured_media_url":"","jetpack_sharing_enabled":true,"jetpack_shortlink":"https:\/\/wp.me\/p4bBYZ-45H","_links":{"self":[{"href":"https:\/\/deepquest.code511.com\/blog\/wp-json\/wp\/v2\/posts\/15729","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/deepquest.code511.com\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/deepquest.code511.com\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/deepquest.code511.com\/blog\/wp-json\/wp\/v2\/users\/439"}],"replies":[{"embeddable":true,"href":"https:\/\/deepquest.code511.com\/blog\/wp-json\/wp\/v2\/comments?post=15729"}],"version-history":[{"count":0,"href":"https:\/\/deepquest.code511.com\/blog\/wp-json\/wp\/v2\/posts\/15729\/revisions"}],"wp:attachment":[{"href":"https:\/\/deepquest.code511.com\/blog\/wp-json\/wp\/v2\/media?parent=15729"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/deepquest.code511.com\/blog\/wp-json\/wp\/v2\/categories?post=15729"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/deepquest.code511.com\/blog\/wp-json\/wp\/v2\/tags?post=15729"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}